{"id":6490,"count":1,"description":"","link":"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/","name":"Le Priove di CamperOnLine","slug":"le-priove-di-camperonline","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le Priove di CamperOnLine Archivi - CamperOnLine Magazine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le Priove di CamperOnLine Archivi - CamperOnLine Magazine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/\" \/>\n<meta property=\"og:site_name\" content=\"CamperOnLine Magazine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.camperonline.it\/magazine\/#website\",\"url\":\"https:\/\/www.camperonline.it\/magazine\/\",\"name\":\"CamperOnLine Magazine\",\"description\":\"Viaggi in camper, test, video, destinazioni, vacanze\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.camperonline.it\/magazine\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/#webpage\",\"url\":\"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/\",\"name\":\"Le Priove di CamperOnLine Archivi - CamperOnLine Magazine\",\"isPartOf\":{\"@id\":\"https:\/\/www.camperonline.it\/magazine\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.camperonline.it\/magazine\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le Priove di CamperOnLine\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le Priove di CamperOnLine Archivi - CamperOnLine Magazine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/","og_locale":"it_IT","og_type":"article","og_title":"Le Priove di CamperOnLine Archivi - CamperOnLine Magazine","og_url":"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/","og_site_name":"CamperOnLine Magazine","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.camperonline.it\/magazine\/#website","url":"https:\/\/www.camperonline.it\/magazine\/","name":"CamperOnLine Magazine","description":"Viaggi in camper, test, video, destinazioni, vacanze","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.camperonline.it\/magazine\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"CollectionPage","@id":"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/#webpage","url":"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/","name":"Le Priove di CamperOnLine Archivi - CamperOnLine Magazine","isPartOf":{"@id":"https:\/\/www.camperonline.it\/magazine\/#website"},"breadcrumb":{"@id":"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.camperonline.it\/magazine\/tag\/le-priove-di-camperonline\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.camperonline.it\/magazine\/"},{"@type":"ListItem","position":2,"name":"Le Priove di CamperOnLine"}]}]}},"_links":{"self":[{"href":"https:\/\/www.camperonline.it\/magazine\/wp-json\/wp\/v2\/tags\/6490"}],"collection":[{"href":"https:\/\/www.camperonline.it\/magazine\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.camperonline.it\/magazine\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.camperonline.it\/magazine\/wp-json\/wp\/v2\/posts?tags=6490"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}